{"id":2,"count":1,"description":"","link":"https:\/\/blog.buritsu.com\/ofune\/category\/%e9%ad%9a%e7%a8%ae\/","name":"\u9b5a\u7a2e","slug":"%e9%ad%9a%e7%a8%ae","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u9b5a\u7a2e \u30a2\u30fc\u30ab\u30a4\u30d6 - \u304a\u3075\u306d\u306b\u306e\u308d\u3046<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.buritsu.com\/ofune\/category\/\u9b5a\u7a2e\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u9b5a\u7a2e \u30a2\u30fc\u30ab\u30a4\u30d6 - \u304a\u3075\u306d\u306b\u306e\u308d\u3046\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.buritsu.com\/ofune\/category\/\u9b5a\u7a2e\/\" \/>\n<meta property=\"og:site_name\" content=\"\u304a\u3075\u306d\u306b\u306e\u308d\u3046\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.buritsu.com\/ofune\/category\/%e9%ad%9a%e7%a8%ae\/\",\"url\":\"https:\/\/blog.buritsu.com\/ofune\/category\/%e9%ad%9a%e7%a8%ae\/\",\"name\":\"\u9b5a\u7a2e \u30a2\u30fc\u30ab\u30a4\u30d6 - \u304a\u3075\u306d\u306b\u306e\u308d\u3046\",\"isPartOf\":{\"@id\":\"https:\/\/blog.buritsu.com\/ofune\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.buritsu.com\/ofune\/category\/%e9%ad%9a%e7%a8%ae\/#breadcrumb\"},\"inLanguage\":\"ja\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.buritsu.com\/ofune\/category\/%e9%ad%9a%e7%a8%ae\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\/\/blog.buritsu.com\/ofune\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u9b5a\u7a2e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.buritsu.com\/ofune\/#website\",\"url\":\"https:\/\/blog.buritsu.com\/ofune\/\",\"name\":\"\u304a\u3075\u306d\u306b\u306e\u308d\u3046\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.buritsu.com\/ofune\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ja\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u9b5a\u7a2e \u30a2\u30fc\u30ab\u30a4\u30d6 - \u304a\u3075\u306d\u306b\u306e\u308d\u3046","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.buritsu.com\/ofune\/category\/\u9b5a\u7a2e\/","og_locale":"ja_JP","og_type":"article","og_title":"\u9b5a\u7a2e \u30a2\u30fc\u30ab\u30a4\u30d6 - \u304a\u3075\u306d\u306b\u306e\u308d\u3046","og_url":"https:\/\/blog.buritsu.com\/ofune\/category\/\u9b5a\u7a2e\/","og_site_name":"\u304a\u3075\u306d\u306b\u306e\u308d\u3046","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.buritsu.com\/ofune\/category\/%e9%ad%9a%e7%a8%ae\/","url":"https:\/\/blog.buritsu.com\/ofune\/category\/%e9%ad%9a%e7%a8%ae\/","name":"\u9b5a\u7a2e \u30a2\u30fc\u30ab\u30a4\u30d6 - \u304a\u3075\u306d\u306b\u306e\u308d\u3046","isPartOf":{"@id":"https:\/\/blog.buritsu.com\/ofune\/#website"},"breadcrumb":{"@id":"https:\/\/blog.buritsu.com\/ofune\/category\/%e9%ad%9a%e7%a8%ae\/#breadcrumb"},"inLanguage":"ja"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.buritsu.com\/ofune\/category\/%e9%ad%9a%e7%a8%ae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/blog.buritsu.com\/ofune\/"},{"@type":"ListItem","position":2,"name":"\u9b5a\u7a2e"}]},{"@type":"WebSite","@id":"https:\/\/blog.buritsu.com\/ofune\/#website","url":"https:\/\/blog.buritsu.com\/ofune\/","name":"\u304a\u3075\u306d\u306b\u306e\u308d\u3046","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.buritsu.com\/ofune\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ja"}]}},"_links":{"self":[{"href":"https:\/\/blog.buritsu.com\/ofune\/wp-json\/wp\/v2\/categories\/2"}],"collection":[{"href":"https:\/\/blog.buritsu.com\/ofune\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.buritsu.com\/ofune\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blog.buritsu.com\/ofune\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}